 {"id":98,"date":"2017-03-31T23:54:13","date_gmt":"2017-03-31T21:54:13","guid":{"rendered":"http:\/\/gap47.astrosurf.com\/?page_id=98"},"modified":"2022-05-03T01:31:35","modified_gmt":"2022-05-02T23:31:35","slug":"calendrier","status":"publish","type":"page","link":"https:\/\/gap47.astrosurf.com\/index.php\/accueil-visiteurs\/calendrier\/","title":{"rendered":"Calendrier des r\u00e9servations"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 20px; color: #808080;\"><strong><span style=\"font-family: arial,helvetica,sans-serif;\">Calendrier des r\u00e9servations programm\u00e9es et des \u00e9v\u00e8nements en cours.<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #993366;\"><strong><span style=\"font-family: arial, helvetica, sans-serif; font-size: 20px;\">Ces r\u00e9servations ne concernent pas les visiteurs du vendredi, mais uniquement les r\u00e9servations des groupes scolaires, des autres groupes associatifs et des groupes priv\u00e9s.<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/calendar.google.com\/calendar\/embed?src=gap47@aliceadsl.fr&amp;ctz=Europe\/Paris\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-738 aligncenter\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/03\/calendrier.jpg\" alt=\"\" width=\"300\" height=\"240\"><\/a><span style=\"font-family: times new roman,times,serif; font-size: 20px;\"><span style=\"font-family: arial black, sans-serif; font-size: 24px;\"><span style=\"color: #ff0000;\">ATTENTION !<\/span><\/span>&nbsp; <strong>Le GAP47 n&rsquo;assurant les visites que gr\u00e2ce \u00e0 des b\u00e9n\u00e9voles en nombre limit\u00e9, il n&rsquo;est pas possible d&rsquo;envisager l&rsquo;inscription de plus de 3 \u00e0 4 classes par mois. Nous sommes d\u00e9sol\u00e9s de cette limitation et vous incitons \u00e0 pr\u00e9voir vos visites le plus t\u00f4t possible dans l&rsquo;ann\u00e9e scolaire.<\/strong><\/span><\/p>\n<hr>\n","protected":false},"excerpt":{"rendered":"<p>Calendrier des r\u00e9servations programm\u00e9es et des \u00e9v\u00e8nements en cours. Ces r\u00e9servations ne concernent pas les visiteurs du vendredi, mais uniquement les r\u00e9servations des groupes scolaires, des autres groupes associatifs et des groupes priv\u00e9s. ATTENTION !&nbsp; Le GAP47 n&rsquo;assurant les visites que gr\u00e2ce \u00e0 des b\u00e9n\u00e9voles en nombre limit\u00e9, il n&rsquo;est pas possible d&rsquo;envisager l&rsquo;inscription de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gap47.astrosurf.com\/index.php\/accueil-visiteurs\/calendrier\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Calendrier des r\u00e9servations&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"parent":29,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-98","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":16,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/98\/revisions"}],"predecessor-version":[{"id":11343,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/98\/revisions\/11343"}],"up":[{"embeddable":true,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/29"}],"wp:attachment":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/media?parent=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}