 {"id":5673,"date":"2017-11-03T00:07:03","date_gmt":"2017-11-02T22:07:03","guid":{"rendered":"http:\/\/gap47.astrosurf.com\/?page_id=5673"},"modified":"2019-12-12T22:27:10","modified_gmt":"2019-12-12T20:27:10","slug":"cerro-paranal","status":"publish","type":"page","link":"https:\/\/gap47.astrosurf.com\/index.php\/ressources\/telescopes-exceptionnels\/telescopes-de-leso\/cerro-paranal\/","title":{"rendered":"Cerro Paranal"},"content":{"rendered":"<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: 24px;\"><strong>\u00c9quipements de l&rsquo;ESO au Chili : Le VLT (Cerro Paranal)<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial,helvetica,sans-serif; font-size: 20px;\"><strong>V<\/strong>ery <strong>L<\/strong>arge <strong>T<\/strong>elescope, sur le Cerro Paranal (altitude : 2635 m)<\/span><strong><br \/>\n<\/strong><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\"><strong>L&rsquo;observatoire astronomique en lumi\u00e8re visible le plus \u00e9volu\u00e9 au monde<\/strong><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_platform.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5631 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_platform.jpg\" alt=\"\" width=\"1600\" height=\"684\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_platform.jpg 1600w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_platform-300x128.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_platform-768x328.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: 'times new roman', times, serif; font-size: 20px;\"><em>\u2191&nbsp; Les 4 UT et trois des 4 AT \u2014 Le site du Cerro Paranal (vue satellite)&nbsp; \u2193<\/em><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Capture-d\u2019e\u0301cran-2017-11-01-a\u0300-09.58.30.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5632 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Capture-d\u2019e\u0301cran-2017-11-01-a\u0300-09.58.30.png\" alt=\"\" width=\"1912\" height=\"1384\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Capture-d\u2019e\u0301cran-2017-11-01-a\u0300-09.58.30.png 1912w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Capture-d\u2019e\u0301cran-2017-11-01-a\u0300-09.58.30-300x217.png 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Capture-d\u2019e\u0301cran-2017-11-01-a\u0300-09.58.30-768x556.png 768w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Capture-d\u2019e\u0301cran-2017-11-01-a\u0300-09.58.30-1658x1200.png 1658w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_camp.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5639 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_camp.jpg\" alt=\"\" width=\"1600\" height=\"514\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_camp.jpg 1600w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_camp-300x96.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Paranal_camp-768x247.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20px;\"><em><span style=\"font-family: times new roman,times,serif;\">En haut \u00e0 gauche : le VLT \u2014 En bas : le camp<\/span> <\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Le <strong class=\"bltxt\">Very Large Telescope array<\/strong> (VLT \u2013 tr\u00e8s grand t\u00e9lescope) est l&rsquo;\u00e9quipement phare de l&rsquo;astronomie europ\u00e9enne en ce d\u00e9but de troisi\u00e8me mill\u00e9naire. Il s&rsquo;agit de l&rsquo;installation observant dans le visible la plus moderne au monde. Le VLT se compose de quatre T\u00e9lescopes Unitaires ayant des miroirs primaires de 8,2 m\u00e8tres de diam\u00e8tre et quatre T\u00e9lescopes Auxiliaires, mobiles, de 1,8 m\u00e8tre. Tous ces t\u00e9lescopes peuvent fonctionner ensemble pour former un \u00ab interf\u00e9rom\u00e8tre \u00bb g\u00e9ant, le VLTI, permettant aux astronomes de discerner des d\u00e9tails avec une pr\u00e9cision jusqu&rsquo;\u00e0 25 fois plus importante qu&rsquo;avec les t\u00e9lescopes utilis\u00e9s s\u00e9par\u00e9ment. Dans le VLTI, les faisceaux lumineux sont combin\u00e9s dans des tunnels souterrains gr\u00e2ce \u00e0 un syst\u00e8me complexe de miroirs. Pour cela, les longueurs des chemins optiques doivent \u00eatre \u00e9galis\u00e9es avec une tol\u00e9rance inf\u00e9rieure au milli\u00e8me de millim\u00e8tre sur une centaine de m\u00e8tres. Le VLTI peut reconstruire des images avec une r\u00e9solution angulaire de quelques milli\u00e8mes de seconde de degr\u00e9. Cela signifie qu&rsquo;en principe, il est possible de distinguer les deux phares d&rsquo;une voiture situ\u00e9e sur la Lune.<\/span><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Les tr\u00e8s grands t\u00e9lescopes ont \u00e9t\u00e9 appel\u00e9s <strong class=\"bltxt\">Antu<\/strong>, <strong class=\"bltxt\">Kueyen<\/strong>, <strong class=\"bltxt\">Melipal<\/strong> et <strong class=\"bltxt\">Yepun<\/strong> (le Soleil, la Lune, la Croix du Sud et V\u00e9nus en dialecte Mapuche).<\/span><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Les T\u00e9lescopes Unitaires de 8,20 m\u00e8tres peuvent aussi \u00eatre utilis\u00e9s s\u00e9par\u00e9ment. Avec un seul de ces t\u00e9lescopes et une pose d&rsquo;une heure, on peut obtenir des images d&rsquo;objets jusqu&rsquo;\u00e0 la magnitude 30. Cela correspond \u00e0 des objets qui sont quatre milliards de fois moins lumineux que ce qui peut \u00eatre vu \u00e0 l&rsquo;\u0153il nu.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5637 aligncenter\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/VLT-data.png\" alt=\"\" width=\"966\" height=\"746\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/VLT-data.png 966w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/VLT-data-300x232.png 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/VLT-data-768x593.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\"><strong>La science avec le VLT<\/strong><\/span><br \/>\n<span style=\"font-family: times new roman,times,serif; font-size: 20px;\"> Le VLT a eu un impact indiscutable sur l&rsquo;astronomie observationnelle. C&rsquo;est l&rsquo;infrastructure \u00ab\u00a0individuelle\u00a0\u00bb au sol la plus productive au monde et les r\u00e9sultats provenant du VLT ont conduit en moyenne \u00e0 plus d&rsquo;une publication scientifique par jour dans une revue \u00e0 comit\u00e9 de lecture. Le VLT contribue au premier plan \u00e0 faire de l&rsquo;ESO l&rsquo;observatoire au sol le plus productif au monde. Le VLT a stimul\u00e9 une nouvelle \u00e8re de d\u00e9couvertes avec plusieurs grandes premi\u00e8res scientifiques, parmi lesquels la premi\u00e8re image d&rsquo;une exoplan\u00e8te (eso0428), l&rsquo;observation du \u00ab voyage \u00bb de plusieurs \u00e9toiles autour du trou noir super-massif au centre de la Voie Lact\u00e9e (eso0846), et l&rsquo;observation des derni\u00e8res lueurs du sursaut gamma le plus \u00e9loign\u00e9 connu \u00e0 ce jour.<\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Laser_Towards_Milky_Ways_Centre.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5638 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Laser_Towards_Milky_Ways_Centre.jpg\" alt=\"\" width=\"2000\" height=\"1816\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Laser_Towards_Milky_Ways_Centre.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Laser_Towards_Milky_Ways_Centre-300x272.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Laser_Towards_Milky_Ways_Centre-768x697.jpg 768w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/Laser_Towards_Milky_Ways_Centre-1322x1200.jpg 1322w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: 'times new roman', times, serif; font-size: 20px;\"><em>\u2191&nbsp; Vis\u00e9e laser vers le centre de la Voie Lact\u00e9e<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\"><strong>Objectifs scientifiques<\/strong><\/span><br \/>\n<span style=\"font-family: times new roman,times,serif; font-size: 20px;\"> Les objectifs g\u00e9n\u00e9raux des t\u00e9lescopes optique\/infrarouge de grande ouverture. Les th\u00e9matiques comprennent les galaxies \u00e0 grand d\u00e9calage vers le rouge (grand redshift), la formation stellaire, les exoplan\u00e8tes et les syst\u00e8mes protoplan\u00e9taires.<\/span><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Les quatre t\u00e9lescopes auxiliaires de 1,8 m (ATs) ont \u00e9t\u00e9 con\u00e7us pour l&rsquo;interf\u00e9rom\u00e9trie et donc essentiellement d\u00e9di\u00e9s au VLTI. Ils ont \u00e9t\u00e9 fabriqu\u00e9s par AMOS (en Belgique). Ils permettent un usage efficace du VLTI chaque nuit puisque, la plupart du temps, les grands t\u00e9lescopes sont utilis\u00e9s pour d&rsquo;autres t\u00e2ches.<\/span><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/ESO-The_Four_ATs_at_Paranal-Phot-51c-06.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5635 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/ESO-The_Four_ATs_at_Paranal-Phot-51c-06.jpg\" alt=\"\" width=\"1181\" height=\"625\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/ESO-The_Four_ATs_at_Paranal-Phot-51c-06.jpg 1181w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/ESO-The_Four_ATs_at_Paranal-Phot-51c-06-300x159.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/08\/ESO-The_Four_ATs_at_Paranal-Phot-51c-06-768x406.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: 'times new roman', times, serif; font-size: 20px;\"><em>\u2191&nbsp; Les quatre \u00ab\u00a0petits t\u00e9lescopes\u00a0\u00bb AT<\/em><\/span><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Ils sont mont\u00e9s sur des rails et peuvent \u00eatre repositionn\u00e9s \u00e0 30 diff\u00e9rentes positions sur la plateforme de l&rsquo;observatoire ce qui permet de changer enti\u00e8rement la configuration des t\u00e9lescopes en fonction de certaines exigences d&rsquo;observation. Depuis ces positions, les rayons lumineux nourrissent le m\u00eame point focal via un syst\u00e8me complexe de miroirs r\u00e9fl\u00e9chissants mont\u00e9 dans un syst\u00e8me de tunnels souterrains.<\/span><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Les t\u00e9lescopes auxiliaires sont plac\u00e9s sous des d\u00f4mes ultra-compacts, avec toute l&rsquo;\u00e9lectronique n\u00e9cessaire, un syst\u00e8me d&rsquo;air conditionn\u00e9, du liquide refroidissant pour le contr\u00f4le thermique, de l&rsquo;air comprim\u00e9, un syst\u00e8me hydraulique pour ouvrir les d\u00f4mes, etc. Chaque AT est aussi dot\u00e9 d&rsquo;un syst\u00e8me de transport qui \u00e9l\u00e8ve et d\u00e9place le t\u00e9lescope et le repositionne d&rsquo;un endroit \u00e0 un autre. Il se d\u00e9place avec sa propre \u00ab\u00a0maison\u00a0\u00bb au sommet du Paranal, presque comme un escargot.<\/span><\/p>\n<p><span style=\"font-family: times new roman,times,serif; font-size: 20px;\">Depuis d\u00e9but 2007 les quatre t\u00e9lescopes auxiliaires sont disponibles et pleinement op\u00e9rationnels.<\/span><\/p>\n<hr>\n<p><strong><span style=\"font-family: times new roman, times, serif; font-size: 20px;\">Quelques photos prises par Philippe Cottin, membre du GAP47 lors de sa visite en d\u00e9but d&rsquo;ann\u00e9e 2017 au Cerro Paranal :<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20px;\"><em><span style=\"font-family: times new roman, times, serif;\">\u2193&nbsp; Les \u00ab\u00a0petits t\u00e9lescopes AT\u00a0\u00bb de 1,80 m du VLT<\/span><\/em><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1804.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6037 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1804.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1804.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1804-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1804-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20px;\"><em><span style=\"font-family: times new roman, times, serif;\">\u2193&nbsp; Les \u00ab\u00a0gros UT\u00a0\u00bb, avec leurs miroirs primaires de 8,20 m de diam\u00e8tre<\/span><\/em><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1850.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6038 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1850.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1850.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1850-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1850-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: 'times new roman', times, serif; font-size: 20px;\"><em>\u2193&nbsp; Le miroir primaire du UT n\u00b0 1 (Antu) et son support<\/em><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6039 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1811.jpg\" alt=\"\" width=\"1125\" height=\"2000\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1811.jpg 1125w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1811-169x300.jpg 169w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1811-768x1365.jpg 768w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1811-675x1200.jpg 675w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: times new roman, times, serif;\"><em><span style=\"font-size: 20px;\">\u2193&nbsp; La salle de contr\u00f4le du N\u00b0 1 (Antu)<\/span><br \/>\n<\/em><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1841.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6040 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1841.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1841.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1841-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1841-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-family: 'times new roman', times, serif; font-size: 20px;\">\u2193&nbsp; La Lune ? Mars ? Non, le sol autour du Cerro Paranal !<\/span><br \/>\n<\/em><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1864.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6041 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1864.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1864.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1864-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1864-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1831.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6042 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1831.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1831.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1831-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1831-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20px;\"><em><span style=\"font-family: times new roman, times, serif;\">\u2191 Technologie de pointe pour la sortie des \u00ab\u00a0images\u00a0\u00bb vers les diverses cam\u00e9ras et instruments d&rsquo;analyse&nbsp; \u2193<\/span><\/em><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1834.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6043 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1834.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1834.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1834-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1834-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1806.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6044 size-full\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1806.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1806.jpg 2000w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1806-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2017\/11\/RIMG1806-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<hr>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 20px;\"><strong>SPECULOOS<\/strong>, sur le Cerro Paranal<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8084\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839a.jpg\" alt=\"\" width=\"2000\" height=\"1333\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839a.jpg 1280w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839a-300x200.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839a-768x512.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839j.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8085\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839j.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839j.jpg 1280w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839j-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839j-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: times new roman, times, serif; font-size: 20px;\">Un tout nouvel observatoire, nomm\u00e9 SPECULOOS, vient d&rsquo;\u00eatre inaugur\u00e9 au Cerro Paranal. Il s&rsquo;agit d&rsquo;un ensemble de 4 t\u00e9lescopes de type Ritchey-Chr\u00e9tien dot\u00e9s chacun d&rsquo;un miroir promaire d&rsquo;un m\u00e8tre de diam\u00e8tre. Ils sont situ\u00e9s un peu plus bas que le VLT. Chaque t\u00e9lescope est \u00e9quip\u00e9 d&rsquo;une monture robotique NTM-1000. Les cam\u00e9ras de SPECULOOS sont dot\u00e9es de d\u00e9tecteurs CCD e2V tr\u00e8s sensibles dans le proche infra-rouge. Les t\u00e9lescopes sont abrit\u00e9s par des d\u00f4mes h\u00e9misph\u00e9riques astronomiques. Les observations robotiques de chacun des quatre t\u00e9lescopes seront contr\u00f4l\u00e9es par le programme ACP Expert.<\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839c.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8086\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839c.jpg\" alt=\"\" width=\"2000\" height=\"1125\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839c.jpg 1280w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839c-300x169.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839c-768x432.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p><span style=\"font-family: times new roman, times, serif; font-size: 20px;\">La \u00ab\u00a0premi\u00e8re lumi\u00e8re\u00a0\u00bb de ces t\u00e9lescopes de Speculoos a eu lieu dans les premiers jours de d\u00e9cembre 2018, avec des tests sur des objets tr\u00e8s connus du ciel profond (voi photos plus bas). Chacun de ces 4 t\u00e9lescopes a le nom d&rsquo;un des 4 satellites galil\u00e9ens de Jupiter : Io, Europa, Ganym\u00e8de et Callisto.<\/span><\/p>\n<p><span style=\"font-family: times new roman, times, serif; font-size: 20px;\">Depuis 1995, des centaines de plan\u00e8tes ont \u00e9t\u00e9 d\u00e9tect\u00e9es en dehors du syst\u00e8me solaire (exoplan\u00e8tes), r\u00e9v\u00e9lant que la majorit\u00e9 des \u00e9toiles de notre Galaxie poss\u00e8dent leur propre syst\u00e8me plan\u00e9taire. En parall\u00e8le \u00e0 ces d\u00e9tections, de nombreux projets ont r\u00e9ussi \u00e0 caract\u00e9riser en d\u00e9tail certaines exoplan\u00e8tes g\u00e9antes, notamment \u00e0 analyser leur atmosph\u00e8re. Appliquer les techniques d\u00e9velopp\u00e9es par ces \u00e9tudes pionni\u00e8res \u00e0 des exoplan\u00e8tes telluriques est la prochaine \u00e9tape pour \u00e9tudier d&rsquo;autres Terres et y chercher la vie.<\/span><\/p>\n<p><span style=\"font-family: times new roman, times, serif; font-size: 20px;\">Afin d&rsquo;ouvrir cette voie, le projet SPECULOOS (<span style=\"color: #0000ff;\"><strong>S<\/strong><\/span>earch for habitable <span style=\"color: #0000ff;\"><strong>P<\/strong><\/span>lanets <span style=\"color: #0000ff;\"><strong>EC<\/strong><\/span>lipsing <span style=\"color: #0000ff;\"><strong>UL<\/strong><\/span>tra-c<span style=\"color: #0000ff;\"><strong>OO<\/strong><\/span>l <span style=\"color: #0000ff;\"><strong>S<\/strong><\/span>tars, recherche de plan\u00e8tes habitables \u00e9clipsant des \u00e9toiles ultra-froides et des naines brunes) vise \u00e0 d\u00e9tecter des plan\u00e8tes telluriques \u00e9clipsant certaines des \u00e9toiles les plus petites et les plus froides du voisinage solaire. Cette strat\u00e9gie est motiv\u00e9e par la possibilit\u00e9 d&rsquo;\u00e9tudier en d\u00e9tail de telles plan\u00e8tes gr\u00e2ce aux futurs observatoires les plus ambitieux comme le t\u00e9lescope g\u00e9ant europ\u00e9en (E-ELT) ou le t\u00e9lescope spatial James Webb (JWST). Les exoplan\u00e8tes d\u00e9tect\u00e9es par SPECULOOS devraient ainsi nous offrir l&rsquo;opportunit\u00e9 d&rsquo;analyser l&rsquo;atmosph\u00e8re de mondes extrasolaires similaires \u00e0 notre Terre, afin notamment d&rsquo;y chercher les traces d&rsquo;une activit\u00e9 biologique.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: times new roman, times, serif; font-size: 20px;\"><em>Premi\u00e8res images obtenues par ces quatre nouveaux t\u00e9lescopes. Les deux premi\u00e8res par le t\u00e9lescope Europa : La n\u00e9buleuse de la Car\u00e8ne (NGC 3372) et la Galaxie M83&nbsp; \u2193<\/em><br \/>\n<\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8088\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b.jpg\" alt=\"\" width=\"2000\" height=\"1992\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b.jpg 1280w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b-150x150.jpg 150w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b-300x300.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b-768x765.jpg 768w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b-1205x1200.jpg 1205w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839b-100x100.jpg 100w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8089\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h.jpg\" alt=\"\" width=\"2001\" height=\"1988\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h.jpg 1280w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h-150x150.jpg 150w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h-300x298.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h-768x763.jpg 768w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h-1208x1200.jpg 1208w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839h-100x100.jpg 100w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 20px;\"><em><span style=\"font-family: times new roman, times, serif;\">\u2193&nbsp;&nbsp; Photo de la \u00ab\u00a0T\u00eate de Cheval\u00a0\u00bb (IC 434) prise par le t\u00e9lescope Callisto<\/span><\/em><\/span><\/p>\n<p><a href=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8091\" src=\"http:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i.jpg\" alt=\"\" width=\"2000\" height=\"1991\" srcset=\"https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i.jpg 1280w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i-150x150.jpg 150w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i-300x300.jpg 300w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i-768x764.jpg 768w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i-1206x1200.jpg 1206w, https:\/\/gap47.astrosurf.com\/wp-content\/uploads\/2018\/12\/eso1839i-100x100.jpg 100w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<hr>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9quipements de l&rsquo;ESO au Chili : Le VLT (Cerro Paranal) &nbsp; Very Large Telescope, sur le Cerro Paranal (altitude : 2635 m) L&rsquo;observatoire astronomique en lumi\u00e8re visible le plus \u00e9volu\u00e9 au monde \u2191&nbsp; Les 4 UT et trois des 4 AT \u2014 Le site du Cerro Paranal (vue satellite)&nbsp; \u2193 En haut \u00e0 gauche : &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gap47.astrosurf.com\/index.php\/ressources\/telescopes-exceptionnels\/telescopes-de-leso\/cerro-paranal\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Cerro Paranal&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"parent":5665,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-5673","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/5673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/comments?post=5673"}],"version-history":[{"count":22,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/5673\/revisions"}],"predecessor-version":[{"id":8969,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/5673\/revisions\/8969"}],"up":[{"embeddable":true,"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/pages\/5665"}],"wp:attachment":[{"href":"https:\/\/gap47.astrosurf.com\/index.php\/wp-json\/wp\/v2\/media?parent=5673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}